{"id":11,"count":13,"description":"Otros tratamientos, algunos de estos de probada eficacia, que deber\u00edan ser considerados como alternativas con lo que ya se conoce.","link":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/","name":"COVID-19 - Tratamientos","slug":"covid-19-tratamientos","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19 - Tratamientos archivos - Consciente con Conciencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19 - Tratamientos archivos - Consciente con Conciencia\" \/>\n<meta property=\"og:description\" content=\"Otros tratamientos, algunos de estos de probada eficacia, que deber\u00edan ser considerados como alternativas con lo que ya se conoce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/\" \/>\n<meta property=\"og:site_name\" content=\"Consciente con Conciencia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/category\\\/covid-19-tratamientos\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/category\\\/covid-19-tratamientos\\\/\",\"name\":\"COVID-19 - Tratamientos archivos - Consciente con Conciencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/category\\\/covid-19-tratamientos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/category\\\/covid-19-tratamientos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19 - Tratamientos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"name\":\"Consciente con Conciencia\",\"description\":\"El bienestar integral es responsabilidad individual, los beneficios son para todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conscienteconconciencia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\",\"name\":\"Consciente con Conciencia\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"contentUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"width\":248,\"height\":248,\"caption\":\"Consciente con Conciencia\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19 - Tratamientos archivos - Consciente con Conciencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/","og_locale":"es_ES","og_type":"article","og_title":"COVID-19 - Tratamientos archivos - Consciente con Conciencia","og_description":"Otros tratamientos, algunos de estos de probada eficacia, que deber\u00edan ser considerados como alternativas con lo que ya se conoce.","og_url":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/","og_site_name":"Consciente con Conciencia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/","url":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/","name":"COVID-19 - Tratamientos archivos - Consciente con Conciencia","isPartOf":{"@id":"https:\/\/conscienteconconciencia.com\/#website"},"breadcrumb":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/conscienteconconciencia.com\/index.php\/category\/covid-19-tratamientos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/conscienteconconciencia.com\/"},{"@type":"ListItem","position":2,"name":"COVID-19 - Tratamientos"}]},{"@type":"WebSite","@id":"https:\/\/conscienteconconciencia.com\/#website","url":"https:\/\/conscienteconconciencia.com\/","name":"Consciente con Conciencia","description":"El bienestar integral es responsabilidad individual, los beneficios son para todos","publisher":{"@id":"https:\/\/conscienteconconciencia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conscienteconconciencia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/conscienteconconciencia.com\/#organization","name":"Consciente con Conciencia","url":"https:\/\/conscienteconconciencia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/","url":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","contentUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","width":248,"height":248,"caption":"Consciente con Conciencia"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}