{"id":1115,"date":"2021-12-15T02:39:04","date_gmt":"2021-12-15T01:39:04","guid":{"rendered":"https:\/\/conscienteconconciencia.wordpress.com\/?p=1115"},"modified":"2021-12-15T02:39:04","modified_gmt":"2021-12-15T01:39:04","slug":"las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19","status":"publish","type":"post","link":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/","title":{"rendered":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19"},"content":{"rendered":"\n<p class=\"has-text-align-justify has-normal-font-size\">En una reciente entrevista con el redactor jefe de LifeSiteNews, John-Henry Westen, el <strong>Dr. Peter McCullough<\/strong>, uno de los m\u00e9dicos m\u00e1s destacados de Estados Unidos en el tratamiento temprano del COVID-19, enumer\u00f3 cinco importantes verdades cient\u00edficas sobre el coronavirus de Wuhan.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-rumble-com wp-block-embed-rumble-com\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Dr. McCullough: 5 most important truths about COVID-19\" src=\"https:\/\/rumble.com\/embed\/vi3sah\/?pub=4#?secret=FDPPu0NCM9\" data-secret=\"FDPPu0NCM9\" width=\"1920\" height=\"1080\" frameborder=\"0\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">McCullough dijo que los siguientes puntos son \u00abcinco mensajes clave de la verdad cient\u00edfica que me gustar\u00eda que todo el mundo entendiera sobre el virus y la pandemia. Son bastante sencillos\u00bb.<br>McCullough tambi\u00e9n habl\u00f3 en la conferencia \u00abStop the Shot\u00bb de la Fundaci\u00f3n Verdad por la Salud, que fue transmitida en vivo por LifeSiteNews, hoy.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"1-el-covid-19-no-se-propaga-de-forma-asintomatica\"><strong>1. El COVID-19 NO se propaga de forma asintom\u00e1tica<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">El Dr. McCullough comenz\u00f3 desmintiendo la creencia com\u00fan de que las personas asintom\u00e1ticas pueden transmitir la enfermedad a otras e insisti\u00f3 en que s\u00f3lo las personas que muestran s\u00edntomas son realmente contagiosas.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">\u00abEl virus no se transmite de forma asintom\u00e1tica. S\u00f3lo los enfermos lo transmiten a otras personas\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"2-las-personas-asintomaticas-no-deben-hacerse-la-prueba\"><strong>2. Las personas asintom\u00e1ticas no deben hacerse la prueba<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">En un segundo punto, abord\u00f3 la cuesti\u00f3n de las pruebas a personas asintom\u00e1ticas, argumentando que esta pr\u00e1ctica genera datos falsos sobre los casos de COVID-19:<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">\u00abTodo lo que estamos haciendo es generar falsos positivos, crear casos adicionales y crear preocupaciones adicionales. La FDA nunca aprob\u00f3 estas pruebas para las pruebas asintom\u00e1ticas. La OMS, a partir del 25 de junio, ha dicho &#8216;no a las pruebas asintom\u00e1ticas'\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">A continuaci\u00f3n, inst\u00f3 a las personas asintom\u00e1ticas a no someterse a las pruebas: \u00abNo deber\u00eda haber ni una sola persona en la tierra que deba someterse a una prueba asintom\u00e1tica&#8230; la gente deber\u00eda pasar de largo por esos puestos de pruebas\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Cuando se le pidi\u00f3 que aclarara si eso tambi\u00e9n se aplica a las pruebas para viajes internacionales, respondi\u00f3: \u00abPor cualquier motivo. Viola las [directivas] de la OMS\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"3-la-inmunidad-natural-es-robusta-completa-y-duradera\"><strong>3. La inmunidad natural es robusta, completa y duradera<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">El tercer punto que abord\u00f3 el Dr. McCullough fue la cuesti\u00f3n de la inmunidad natural, que calific\u00f3 de \u00abrobusta, completa y duradera\u00bb, descartando as\u00ed cualquier temor a que se pueda contraer un caso grave de la enfermedad m\u00e1s de una vez y rechazando otro mito com\u00fan sobre la COVID.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">\u00abNo hay ninguna posibilidad significativa de que se produzca un segundo caso grave de COVID\u00bb, dijo McCullough a LifeSite. \u00abDe hecho, nunca se ha producido un caso confirmado hasta ahora en el mundo\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">A continuaci\u00f3n, se refiri\u00f3 a los numerosos casos notificados de personas que han contra\u00eddo el COVID m\u00e1s de una vez, declarando: \u00abcualquiera de los supuestos casos que han surgido han implicado una mala interpretaci\u00f3n de una prueba de PCR falsa positiva. Esto no ocurre. Si ocurriera, habr\u00edamos visto a miles, si no millones, de personas hospitalizadas una y otra vez por COVID-19. No ha ocurrido. Fundamentalmente no ocurre\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Para ilustrar su tercer punto de forma a\u00fan m\u00e1s clara, concluy\u00f3 su comentario sobre la inmunidad natural con la siguiente imagen: \u00abAlguien que es naturalmente inmune puede acercarse a alguien con COVID-19, recibir una gran tos en la cara, y no va a contraer la enfermedad\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"4-el-covid-19-sea-cual-sea-su-variante-es-facilmente-tratable-en-casa\"><strong>4. El COVID-19, sea cual sea su variante, es f\u00e1cilmente tratable en casa<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">El tratamiento de la COVID-19 ha sido el centro del trabajo del Dr. McCullough desde el comienzo de la pandemia.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">El a\u00f1o pasado fue censurado en YouTube por promover un tratamiento que podr\u00eda haber reducido las muertes en un 85%.<br><br>Reiter\u00f3 una vez m\u00e1s que el tratamiento temprano puede marcar la diferencia entre la vida y la muerte: \u00abAlrededor del 85% de las hospitalizaciones y muertes son completamente evitables con un tratamiento temprano. La \u00fanica forma de que la gente acabe en el hospital y lo pase mal es que no reciba ning\u00fan tratamiento: no se enferma o no se le ofrece tratamiento y acaba ingresando en el hospital despu\u00e9s de estar enfermo dos semanas en casa\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Tambi\u00e9n inst\u00f3 a las personas que contraen el COVID-19 a no esperar para buscar tratamiento, insistiendo en que \u00abcualquier persona con sentido com\u00fan deber\u00eda entender que es f\u00e1cil tratar la enfermedad cuando es temprana y los s\u00edntomas son leves. Se agrava progresivamente a medida que la gente avanza en la enfermedad\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Concluy\u00f3 su cuarto punto lamentando que la hospitalizaci\u00f3n y la falta de tratamiento sean a menudo sin\u00f3nimo de muerte: \u00abAl final la gente muere de co\u00e1gulos. Y es muy dif\u00edcil revertirlos. Por eso, si esperamos a la hospitalizaci\u00f3n, es demasiado tarde. Si esperamos a que los niveles de ox\u00edgeno sean bajos debido a los co\u00e1gulos de sangre en los pulmones, es demasiado tarde\u00bb.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"5-las-actuales-vacunas-covid-19-son-obsoletas-y-deben-considerarse-no-aptas-para-el-uso-humano\"><strong>5. Las actuales vacunas COVID-19 son obsoletas y deben considerarse no aptas para el uso humano<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Por \u00faltimo, el m\u00e9dico abord\u00f3 la cuesti\u00f3n de las vacunas COVID.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">Seg\u00fan McCullough, las vacunas actualmente disponibles -como las de AstraZeneca, Johnson &amp; Johnson, Pfizer y Moderna- son \u00abobsoletas\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-normal-font-size\">\u00abNo cubren las nuevas variantes; los pacientes est\u00e1n fallando con estas vacunas. Est\u00e1n siendo hospitalizados y enfermando a pesar de haber recibido las vacunas\u00bb, dijo, y a\u00f1adi\u00f3 que \u00ablas vacunas en este momento han supuesto un r\u00e9cord de mortalidad y lesiones y deber\u00edan considerarse inseguras y no aptas para el uso humano.\u00bb<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.lifesitenews.com\/news\/dr-peter-mcculloughs-5-most-important-truths-about-covid-19\/\" target=\"_blank\" rel=\"noreferrer noopener\">ver editorial en linea<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una reciente entrevista con el redactor jefe de LifeSiteNews, John-Henry Westen, el Dr. Peter McCullough, uno de los m\u00e9dicos m\u00e1s destacados de Estados Unidos en el tratamiento temprano del COVID-19, enumer\u00f3 cinco importantes verdades cient\u00edficas sobre el coronavirus de Wuhan. McCullough dijo que los siguientes puntos son \u00abcinco mensajes clave de la verdad cient\u00edfica &hellip; <a href=\"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[38],"class_list":["post-1115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19-cientificos","category-covid-19-tratamientos","tag-peter-mccullough"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia\" \/>\n<meta property=\"og:description\" content=\"En una reciente entrevista con el redactor jefe de LifeSiteNews, John-Henry Westen, el Dr. Peter McCullough, uno de los m\u00e9dicos m\u00e1s destacados de Estados Unidos en el tratamiento temprano del COVID-19, enumer\u00f3 cinco importantes verdades cient\u00edficas sobre el coronavirus de Wuhan. McCullough dijo que los siguientes puntos son \u00abcinco mensajes clave de la verdad cient\u00edfica &hellip; Sigue leyendo Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Consciente con Conciencia\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T01:39:04+00:00\" \/>\n<meta name=\"author\" content=\"nochichfrei\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nochichfrei\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/\"},\"author\":{\"name\":\"nochichfrei\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/person\\\/54d44799d1e164549bc68f5e72897d9e\"},\"headline\":\"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19\",\"datePublished\":\"2021-12-15T01:39:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/\"},\"wordCount\":919,\"publisher\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/peter-mccullough.jpg\",\"keywords\":[\"Peter McCullough\"],\"articleSection\":[\"COVID-19 - Cient\u00edficos\",\"COVID-19 - Tratamientos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/\",\"name\":\"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/peter-mccullough.jpg\",\"datePublished\":\"2021-12-15T01:39:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/peter-mccullough.jpg\",\"contentUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/peter-mccullough.jpg\",\"width\":810,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2021\\\/12\\\/15\\\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"name\":\"Consciente con Conciencia\",\"description\":\"El bienestar integral es responsabilidad individual, los beneficios son para todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conscienteconconciencia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\",\"name\":\"Consciente con Conciencia\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"contentUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"width\":248,\"height\":248,\"caption\":\"Consciente con Conciencia\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/person\\\/54d44799d1e164549bc68f5e72897d9e\",\"name\":\"nochichfrei\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"caption\":\"nochichfrei\"},\"sameAs\":[\"https:\\\/\\\/conscienteconconciencia.com\"],\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/author\\\/nochichfrei\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia","og_description":"En una reciente entrevista con el redactor jefe de LifeSiteNews, John-Henry Westen, el Dr. Peter McCullough, uno de los m\u00e9dicos m\u00e1s destacados de Estados Unidos en el tratamiento temprano del COVID-19, enumer\u00f3 cinco importantes verdades cient\u00edficas sobre el coronavirus de Wuhan. McCullough dijo que los siguientes puntos son \u00abcinco mensajes clave de la verdad cient\u00edfica &hellip; Sigue leyendo Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19","og_url":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/","og_site_name":"Consciente con Conciencia","article_published_time":"2021-12-15T01:39:04+00:00","author":"nochichfrei","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nochichfrei","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#article","isPartOf":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/"},"author":{"name":"nochichfrei","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/person\/54d44799d1e164549bc68f5e72897d9e"},"headline":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19","datePublished":"2021-12-15T01:39:04+00:00","mainEntityOfPage":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/"},"wordCount":919,"publisher":{"@id":"https:\/\/conscienteconconciencia.com\/#organization"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/12\/peter-mccullough.jpg","keywords":["Peter McCullough"],"articleSection":["COVID-19 - Cient\u00edficos","COVID-19 - Tratamientos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/","url":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/","name":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19 - Consciente con Conciencia","isPartOf":{"@id":"https:\/\/conscienteconconciencia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/12\/peter-mccullough.jpg","datePublished":"2021-12-15T01:39:04+00:00","breadcrumb":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#primaryimage","url":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/12\/peter-mccullough.jpg","contentUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/12\/peter-mccullough.jpg","width":810,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2021\/12\/15\/las-5-verdades-mas-importantes-del-dr-peter-mccullough-sobre-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/conscienteconconciencia.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 verdades m\u00e1s importantes del Dr. Peter McCullough sobre COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/conscienteconconciencia.com\/#website","url":"https:\/\/conscienteconconciencia.com\/","name":"Consciente con Conciencia","description":"El bienestar integral es responsabilidad individual, los beneficios son para todos","publisher":{"@id":"https:\/\/conscienteconconciencia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conscienteconconciencia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/conscienteconconciencia.com\/#organization","name":"Consciente con Conciencia","url":"https:\/\/conscienteconconciencia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/","url":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","contentUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","width":248,"height":248,"caption":"Consciente con Conciencia"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/person\/54d44799d1e164549bc68f5e72897d9e","name":"nochichfrei","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","caption":"nochichfrei"},"sameAs":["https:\/\/conscienteconconciencia.com"],"url":"https:\/\/conscienteconconciencia.com\/index.php\/author\/nochichfrei\/"}]}},"_links":{"self":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/comments?post=1115"}],"version-history":[{"count":0,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts\/1115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/media\/1117"}],"wp:attachment":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/categories?post=1115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/tags?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}