{"id":1179,"date":"2022-01-03T02:15:00","date_gmt":"2022-01-03T01:15:00","guid":{"rendered":"https:\/\/conscienteconconciencia.wordpress.com\/?p=1179"},"modified":"2022-01-03T02:15:00","modified_gmt":"2022-01-03T01:15:00","slug":"ante-la-criminalizacion-de-los-no-vacunados","status":"publish","type":"post","link":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/","title":{"rendered":"Ante la criminalizaci\u00f3n de los no vacunados?"},"content":{"rendered":"\n<p class=\"has-text-align-justify has-medium-font-size\" id=\"deutsche-welle-publico-una-editorial-que-a-mi-modo-de-ver-reflejaria-una-tendencia-peligrosa-que-vengo-observando-desde-algun-tiempo-y-como-se-mencionan-algunos-entornos-que-me-son-familiares-la-he-leido-detenidamente-evitando-tomar-este-analisis-como-si-se-tratara-de-un-ataque-a-mi-o-a-mis-valores\"><strong>Deutsche Welle<\/strong> (1) public\u00f3 una editorial que a mi modo de ver reflejar\u00eda una tendencia peligrosa que vengo observando desde algun tiempo y como se mencionan algunos entornos que me son familiares la he le\u00eddo detenidamente evitando tomar este an\u00e1lisis como si se tratara de un ataque (por lo menos por ahora) a mi o a mis valores.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/dw.com\/es\/coronavirus-y-conspiraciones-qu\u00e9-rol-juegan-el-esoterismo-y-la-espiritualidad\/a-60298506\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/conscienteconconciencia.files.wordpress.com\/2022\/01\/esoterismo-y-la-espiritualidad1.png?w=727\" alt=\"\" class=\"wp-image-1177\" width=\"601\" height=\"563\" srcset=\"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad1.png 727w, https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad1-300x281.png 300w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/a><figcaption>Clic sobre la imagen para leer la editorial de DW<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify has-medium-font-size\">Ante el t\u00edtulo de la editorial:<strong> \u201c<a href=\"https:\/\/www.dw.com\/es\/coronavirus-y-conspiraciones-qu\u00e9-rol-juegan-el-esoterismo-y-la-espiritualidad\/a-60298506\" target=\"_blank\" rel=\"noreferrer noopener\">Coronavirus y conspiraciones: \u00bfqu\u00e9 rol juegan el esoterismo y la espiritualidad?<\/a>\u201d<\/strong> lo primero que me propongo es buscar la definici\u00f3n de ambos t\u00e9rminos: <strong>esoterismo<\/strong> y <strong>espiritualidad<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.significados.com\/esoterismo\/\" target=\"_blank\"><em><strong>Qu\u00e9 es Esoterismo?<\/strong><\/em><\/a><br>\u00ab<em>El esoterismo es un conjunto de conocimientos ocultos a los sentidos e impenetrable para la mente por lo tanto dif\u00edcil de entender. Esoterismo proviene de la combinaci\u00f3n de la ra\u00edz griega eso que significa lado interior con el sufijo -ismo que se define como los conocimientos enmarcados dentro de una serie de tradiciones, doctrinas, ense\u00f1anzas y \/ o ritos.<br>Es sin\u00f3nimo de algo oculto y misterioso porque antiguamente las ense\u00f1anzas eran transmitidas oralmente y solo para los iniciados manteniendo un secretismo. Se asocia las pr\u00e1cticas de magia, alquimia y astrolog\u00eda a lo esot\u00e9rico que al no tener una base en m\u00e9todos cient\u00edficos tradicionales han sido considerados subjetivos y un <span style=\"text-decoration:underline;\">adjetivo despectivo<\/span>.<\/em>\u00ab<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong><a href=\"https:\/\/www.significados.com\/espiritualidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u00e9 es Espiritualidad?<\/a><\/strong><br>\u00abLa espiritualidad es el conocimiento, aceptaci\u00f3n o cultivo de la esencia inmaterial de uno mismo. Palabra que deriva del griego y que est\u00e1 compuesta por la voz spiritus que significa &#8216;respiro&#8217;, -alis, que se refiere a &#8216;lo relativo a&#8217;, y el sufijo -dad, que indica cualidad, por lo tanto, etimol\u00f3gicamente, espiritualidad es todo lo relativo a la cualidad de lo espiritual o esp\u00edritu.\u00bb<\/em><br><\/p>\n\n\n\n<p class=\"has-text-align-justify has-medium-font-size\">Conociendo ahora el significado de estas palabras me pregunto porque utilizar estos t\u00e9rminos que son tan amplios y no se corresponden a una comunidad especifica o perfectamente identificable (en lo que respecta a colectivos sociales) estableciendo as\u00ed una co-relaci\u00f3n entre los individuos que tienen una postura determinada sobre el tema tan complejo que estamos viviendo y otros grupos extremistas. <br>Debemos destacar que muchas personas siendo parte de la poblaci\u00f3n cr\u00edtica no as\u00ed se ubican en grupos esot\u00e9ricos y\/o espirituales, incluso forman parte de la comunidad cient\u00edfica y m\u00e9dica internacional.<br><br>Entonces ante la premisa: <strong>\u201c\u00bfqu\u00e9 rol juegan el esoterismo y la espiritualidad?\u201d<\/strong>, yo dir\u00eda que juegan tanto como el rol de los: vegetarianos, artistas, m\u00fasicos, deportistas, religiosos, docentes, padres de familia, artesanos, cient\u00edficos, investigadores, pol\u00edticos, empresarios, campesinos, comerciantes, m\u00e9dicos, militares, universitarios y gente de las m\u00e1s diversas profesiones, oficios y or\u00edgenes.<br><br>Entonces leyendo detenidamente esa editorial se estar\u00eda estableciendo una <span style=\"text-decoration:underline;\">asociaci\u00f3n sutil<\/span> entre gente que forma parte o no de una filosof\u00eda esot\u00e9rica y\/o espiritual con los denominados grupos de \u201cultraderecha\u201d.<br>Por \u00faltimo es necesario citar una definici\u00f3n posible de las tantas para el t\u00e9rmino: <strong>ultraderecha<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\"><em><strong><a href=\"https:\/\/www.elconfidencial.com\/mundo\/europa\/2019-01-12\/que-significa-ser-de-ultraderecha-en-pleno-siglo-xxi_1746174\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u00e9 es la ultraderecha?<\/a><\/strong><br>\u201cYa que el ultraderechismo no cuenta con un concepto ideol\u00f3gico homog\u00e9neo, tampoco hay una definici\u00f3n uniforme para el t\u00e9rmino\u201d, escribe Gabriele Nandlinger, periodista especializada en extremismos derechistas del portal alem\u00e1n &#8216;Blick nach Rechts&#8217;. \u201cPor lo general, los ultraderechistas rechazan el orden democr\u00e1tico y liberal -incluso a trav\u00e9s del uso de la violencia- y quieren construir un sistema estatal autoritario o incluso totalitario, en el que una ideolog\u00eda nacionalista y racista deber\u00eda servir de base para el orden social\u201d.<br>Algunos partidos o l\u00edderes pol\u00edticos como: Donald Trump (E.E.U.U), Jair Bolsonaro (Brasil), AfD (Alemania) y VOX (Espa\u00f1a) forman parte del tan temido espectro con el que se busca esta asociaci\u00f3n tan cuestionable.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-justify has-medium-font-size\" id=\"(2)\">Esto es a mi entender lo <span style=\"text-decoration:underline;\"><strong>m\u00e1s peligroso de toda la editorial<\/strong><\/span>, que por supuesto incluye varios p\u00e1rrafos m\u00e1s cuestionables.<br>El porque mi preocupaci\u00f3n? porque se est\u00e1 estigmatizando (2) a un grupo de miles (tal ves millones) de personas y el l\u00edmite de esta estigmatizaci\u00f3n y la criminalizaci\u00f3n es muy delgado. Hay ya evidencias de este proceso en diversos pa\u00edses del mundo.<br><br>A comienzos del a\u00f1o 2019 (un a\u00f1o antes de declararse la Pandemia por COVID-19), la <strong>Organizaci\u00f3n Mundial de la Salud<\/strong> public\u00f3 (3) una lista con las 10 amenazas para la salud global y una de ellas era: \u201cRenuencia a la vacunaci\u00f3n\u201d. Por supuesto de inmediato la prensa lo replico y difundi\u00f3 bajo el termino: \u201cmovimiento antivacunas\u201d(4).<br>El ministro del interior alem\u00e1n <strong>Horst Seehofer<\/strong> durante la presentaci\u00f3n del informe sobre 2020 (5) de la Oficina Federal para la Protecci\u00f3n de la Constituci\u00f3n (la agencia de inteligencia policial alemana), en uno de sus p\u00e1rrafos declar\u00f3: \u201c<em>pese a que el a\u00f1o pasado se cancelaron muchas reuniones importantes del entorno de la ultraderecha, estos extremistas consiguieron infiltrarse entre la ciudadan\u00eda que protestaba contra las restricciones del Coronavirus.<\/em>\u201d<br><br>Y as\u00ed es como comienza a establecerse un concepto que por la fuerza de la repetici\u00f3n puede llegar a convertirse en una \u201cverdad\u201d. Dicha criminalizaci\u00f3n pone un manto de sospecha sobre colectivos de ciudadanos que s\u00f3lo reclaman por su libertad y el derecho natural en relaci\u00f3n a la salud en su propio cuerpo.<br><br>En la medida que este tipo de procesos no sean identificados a tiempo y expuestos para su discusi\u00f3n democr\u00e1tica, estaremos yendo en una direcci\u00f3n muy peligrosa que desde un punto de vista social, podr\u00e1 cobrarse (en un futuro no muy lejano) la vida o por lo menos las libertades individuales de una gran parte de la poblaci\u00f3n humana. <br>Para cuando esto suceda ya no habr\u00e1 necesidad de buscar entonces una respuesta a la pregunta inicial, porque ya habr\u00e1 sido demasiado tarde.<\/p>\n\n\n\n<p><br><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.dw.com\/es\/coronavirus-y-conspiraciones-qu%C3%A9-rol-juegan-el-esoterismo-y-la-espiritualidad\/a-60298506\" target=\"_blank\">Acceder a la nota editorial en linea<\/a><\/strong><br><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Referencias:<\/strong><br><strong>(1)<\/strong> <strong>DW<\/strong> es una emisora alemana, financiada por el presupuesto fiscal federal alem\u00e1n.<\/p>\n\n\n\n<p class=\"has-text-align-justify has-small-font-size\"><strong>(2)<\/strong> Por lo general se habla de estigmatizaci\u00f3n en el \u00e1mbito de la sociolog\u00eda. Para esta ciencia, un estigma es una caracter\u00edstica o un atributo que hace que el individuo que lo porta sea considerado como parte de un grupo inferior, inaceptable o negativo.<br>La estigmatizaci\u00f3n, en este marco, consiste en atribuir un rasgo de este tipo a una persona o a un grupo social. Los sujetos estigmatizados son discriminados y rechazados, pudiendo ser v\u00edctimas de agresiones verbales o maltrato f\u00edsico. En algunos casos la estigmatizaci\u00f3n puede derivar en asesinatos.<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>(3)<\/strong> https:\/\/www.who.int\/es\/news-room\/spotlight\/ten-threats-to-global-health-in-2019<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>(4)<\/strong> https:\/\/www.libertaddigital.com\/ciencia-tecnologia\/salud\/2021-05-23\/el-lobby-antivacunas-en-espana-quienes-son-y-cual-es-su-objetivo-6757700\/<\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>(5)<\/strong> https:\/\/elpais.com\/internacional\/2021-06-15\/alemania-detecta-un-peligroso-aumento-del-extremismo-de-derechas-durante-la-pandemia.html<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutsche Welle (1) public\u00f3 una editorial que a mi modo de ver reflejar\u00eda una tendencia peligrosa que vengo observando desde algun tiempo y como se mencionan algunos entornos que me son familiares la he le\u00eddo detenidamente evitando tomar este an\u00e1lisis como si se tratara de un ataque (por lo menos por ahora) a mi o &hellip; <a href=\"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Ante la criminalizaci\u00f3n de los no vacunados?<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[23],"class_list":["post-1179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19-legales","category-covid-19-sociedad","tag-covid-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia\" \/>\n<meta property=\"og:description\" content=\"Deutsche Welle (1) public\u00f3 una editorial que a mi modo de ver reflejar\u00eda una tendencia peligrosa que vengo observando desde algun tiempo y como se mencionan algunos entornos que me son familiares la he le\u00eddo detenidamente evitando tomar este an\u00e1lisis como si se tratara de un ataque (por lo menos por ahora) a mi o &hellip; Sigue leyendo Ante la criminalizaci\u00f3n de los no vacunados?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/\" \/>\n<meta property=\"og:site_name\" content=\"Consciente con Conciencia\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-03T01:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conscienteconconciencia.files.wordpress.com\/2022\/01\/esoterismo-y-la-espiritualidad1.png?w=727\" \/>\n<meta name=\"author\" content=\"nochichfrei\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nochichfrei\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/\"},\"author\":{\"name\":\"nochichfrei\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/person\\\/54d44799d1e164549bc68f5e72897d9e\"},\"headline\":\"Ante la criminalizaci\u00f3n de los no vacunados?\",\"datePublished\":\"2022-01-03T01:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/\"},\"wordCount\":1125,\"publisher\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/esoterismo-y-la-espiritualidad2.png\",\"keywords\":[\"COVID-19\"],\"articleSection\":[\"COVID-19 - Legales\",\"COVID-19 - Sociedad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/\",\"name\":\"Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/esoterismo-y-la-espiritualidad2.png\",\"datePublished\":\"2022-01-03T01:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/esoterismo-y-la-espiritualidad2.png\",\"contentUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/esoterismo-y-la-espiritualidad2.png\",\"width\":719,\"height\":532},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/2022\\\/01\\\/03\\\/ante-la-criminalizacion-de-los-no-vacunados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ante la criminalizaci\u00f3n de los no vacunados?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#website\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"name\":\"Consciente con Conciencia\",\"description\":\"El bienestar integral es responsabilidad individual, los beneficios son para todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conscienteconconciencia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#organization\",\"name\":\"Consciente con Conciencia\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"contentUrl\":\"https:\\\/\\\/conscienteconconciencia.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cropped-cropped-logo2.jpg\",\"width\":248,\"height\":248,\"caption\":\"Consciente con Conciencia\"},\"image\":{\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/conscienteconconciencia.com\\\/#\\\/schema\\\/person\\\/54d44799d1e164549bc68f5e72897d9e\",\"name\":\"nochichfrei\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g\",\"caption\":\"nochichfrei\"},\"sameAs\":[\"https:\\\/\\\/conscienteconconciencia.com\"],\"url\":\"https:\\\/\\\/conscienteconconciencia.com\\\/index.php\\\/author\\\/nochichfrei\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/","og_locale":"es_ES","og_type":"article","og_title":"Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia","og_description":"Deutsche Welle (1) public\u00f3 una editorial que a mi modo de ver reflejar\u00eda una tendencia peligrosa que vengo observando desde algun tiempo y como se mencionan algunos entornos que me son familiares la he le\u00eddo detenidamente evitando tomar este an\u00e1lisis como si se tratara de un ataque (por lo menos por ahora) a mi o &hellip; Sigue leyendo Ante la criminalizaci\u00f3n de los no vacunados?","og_url":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/","og_site_name":"Consciente con Conciencia","article_published_time":"2022-01-03T01:15:00+00:00","og_image":[{"url":"https:\/\/conscienteconconciencia.files.wordpress.com\/2022\/01\/esoterismo-y-la-espiritualidad1.png?w=727","type":"","width":"","height":""}],"author":"nochichfrei","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nochichfrei","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#article","isPartOf":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/"},"author":{"name":"nochichfrei","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/person\/54d44799d1e164549bc68f5e72897d9e"},"headline":"Ante la criminalizaci\u00f3n de los no vacunados?","datePublished":"2022-01-03T01:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/"},"wordCount":1125,"publisher":{"@id":"https:\/\/conscienteconconciencia.com\/#organization"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#primaryimage"},"thumbnailUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad2.png","keywords":["COVID-19"],"articleSection":["COVID-19 - Legales","COVID-19 - Sociedad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/","url":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/","name":"Ante la criminalizaci\u00f3n de los no vacunados? - Consciente con Conciencia","isPartOf":{"@id":"https:\/\/conscienteconconciencia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#primaryimage"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#primaryimage"},"thumbnailUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad2.png","datePublished":"2022-01-03T01:15:00+00:00","breadcrumb":{"@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#primaryimage","url":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad2.png","contentUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2022\/01\/esoterismo-y-la-espiritualidad2.png","width":719,"height":532},{"@type":"BreadcrumbList","@id":"https:\/\/conscienteconconciencia.com\/index.php\/2022\/01\/03\/ante-la-criminalizacion-de-los-no-vacunados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/conscienteconconciencia.com\/"},{"@type":"ListItem","position":2,"name":"Ante la criminalizaci\u00f3n de los no vacunados?"}]},{"@type":"WebSite","@id":"https:\/\/conscienteconconciencia.com\/#website","url":"https:\/\/conscienteconconciencia.com\/","name":"Consciente con Conciencia","description":"El bienestar integral es responsabilidad individual, los beneficios son para todos","publisher":{"@id":"https:\/\/conscienteconconciencia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conscienteconconciencia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/conscienteconconciencia.com\/#organization","name":"Consciente con Conciencia","url":"https:\/\/conscienteconconciencia.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/","url":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","contentUrl":"https:\/\/conscienteconconciencia.com\/wp-content\/uploads\/2021\/11\/cropped-cropped-logo2.jpg","width":248,"height":248,"caption":"Consciente con Conciencia"},"image":{"@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/conscienteconconciencia.com\/#\/schema\/person\/54d44799d1e164549bc68f5e72897d9e","name":"nochichfrei","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9c51c01e438bc4207024f2ea5663d0df664d518293d659b77906547652aa4594?s=96&d=mm&r=g","caption":"nochichfrei"},"sameAs":["https:\/\/conscienteconconciencia.com"],"url":"https:\/\/conscienteconconciencia.com\/index.php\/author\/nochichfrei\/"}]}},"_links":{"self":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts\/1179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/comments?post=1179"}],"version-history":[{"count":0,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/posts\/1179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/media\/1178"}],"wp:attachment":[{"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/media?parent=1179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/categories?post=1179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conscienteconconciencia.com\/index.php\/wp-json\/wp\/v2\/tags?post=1179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}